{"id":263,"date":"2017-09-19T16:35:42","date_gmt":"2017-09-19T14:35:42","guid":{"rendered":"http:\/\/www.pure-ocean.org\/?page_id=263"},"modified":"2025-04-29T12:48:07","modified_gmt":"2025-04-29T10:48:07","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/www.pure-ocean.org\/en\/mentions-legales\/","title":{"rendered":"Mentions l\u00e9gales"},"content":{"rendered":"<div style='padding-bottom:10px;' class='av-special-heading av-special-heading-h1     '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >fonds de dotation Pure Ocean<\/h1><div class='special-heading-border'><div class='special-heading-inner-border' ><\/div><\/div><\/div>\n<div style='height:30px' class='hr hr-invisible  '><span class='hr-inner ' ><span class='hr-inner-style'><\/span><\/span><\/div>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '   itemprop=\"text\" ><h2><span style=\"font-size: 14pt;\"><a href=\"https:\/\/www.pure-ocean.org\/en\/privacy-policy\/\"><strong>Politique de confidentialit\u00e9 de Pure Ocean : cliquez ici<\/strong><\/a><\/span><\/h2>\n<\/div><\/section>\n<div style='height:30px' class='hr hr-invisible  '><span class='hr-inner ' ><span class='hr-inner-style'><\/span><\/span><\/div>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock  '   itemprop=\"text\" ><h2><span style=\"font-size: 14pt;\"><strong>Mentions l\u00e9gales<\/strong><\/span><\/h2>\n<p><strong style=\"font-size: 0.9rem;\">Si\u00e8ge social :<\/strong><\/p>\n<p>8 Boulevard Edouard Herriot \u2013 13008 MARSEILLE<\/p>\n<p>Num\u00e9ro de SIRET : 850 247 040 00015<\/p>\n<p><strong>Hebergeur :<\/strong><\/p>\n<p>OVH &#8211; \u00a0Si\u00e8ge social : 2 rue Kellermann &#8211; 59100 Roubaix \u2013 France \/ Tel : 09 72 10 10 07<\/p>\n<p><strong>Directeur de la publication :<\/strong><\/p>\n<p>Mr David SUSSMANN<\/p>\n<h3><strong style=\"font-size: 0.9rem;\">Statuts :<\/strong><\/h3>\n<p><strong style=\"font-size: 0.9rem;\">Article 1er : DENOMINATION<\/strong><\/p>\n<p>Le fonds de dotation a pour d\u00e9nomination : \u00ab FONDS DE DOTATION PURE OCEAN \u00bb.<\/p>\n<p><strong>Article 2 : OBJET<\/strong><\/p>\n<p>Le fonds de dotation a pour objet de favoriser, de soutenir et de d\u00e9velopper des activit\u00e9s d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral \u00e0 caract\u00e8re \u00e9cologique, humanitaire, social, culturel, \u00e9ducatif et\/ou philanthropique, en France ou \u00e0 l\u2019\u00e9tranger, visant notamment \u00e0\u00a0:<\/p>\n<p>la protection des oc\u00e9ans ;<br \/>\nle financement de projets innovants pour la connaissance et la pr\u00e9servation de la biodiversit\u00e9 marine et des \u00e9cosyst\u00e8mes fragiles\u00a0;<br \/>\nla sensibilisation du grand public aux enjeux environnementaux des oc\u00e9ans<\/p>\n<p>Dans ce cadre, le fonds a pour ambition de mener ces actions soit directement aupr\u00e8s des personnes ou des projets concern\u00e9s, soit indirectement par le biais du financement de structures poursuivant le m\u00eame objet et\/ou partageant les m\u00eames valeurs.<\/p>\n<p>Il pourra \u00e9galement constituer et g\u00e9rer des fonds individualis\u00e9s d\u00e9di\u00e9s au financement d\u2019activit\u00e9s vis\u00e9es au premier alin\u00e9a du pr\u00e9sent article.<\/p>\n<p><strong>Article 3 : MOYENS D\u2019ACTION<\/strong><\/p>\n<p>Dans le cadre de son objet social vis\u00e9 \u00e0 l\u2019article 2, le fonds pourra notamment employer en France ou \u00e0 l\u2019\u00e9tranger les moyens suivants\u00a0:<\/p>\n<p>Apporter du soutien mat\u00e9riel et\/ou organisationnel et\/ou logistique \u00e0 toute personne morale d\u00e9veloppant des activit\u00e9s similaires ou connexes\u00a0;<br \/>\nD\u00e9velopper des partenariats avec tout organisme d\u00e9veloppant des activit\u00e9s similaires ou connexes\u00a0;<br \/>\nSoutenir tout organisme d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral ou \u00e9ligible \u00e0 un r\u00e9gime de m\u00e9c\u00e9nat poursuivant des buts similaires aux siens ou se situant dans le prolongement de son objet\u00a0;<br \/>\nSoutenir toute forme de recherches en lien avec son objet (attribution de prix, attribution de bourse, financement de th\u00e8ses, \u2026)\u00a0;<br \/>\nMettre en place toute communication (revue, publication d\u2019ouvrages, site internet, manifestations, colloques, formations, s\u00e9minaires, etc.) visant \u00e0 promouvoir son objet ;<br \/>\nProc\u00e9der par tout moyen \u00e0 la collecte de fonds visant \u00e0 favoriser le d\u00e9veloppement de ses activit\u00e9s en lien avec son objet social\u00a0;<br \/>\nEffectuer du b\u00e9n\u00e9volat au sein de structures poursuivant des buts similaires au sien ou se situant dans le prolongement de son objet\u00a0;<br \/>\nEngager du personnel qualifi\u00e9 pour permettre la r\u00e9alisation de son objet\u00a0;<br \/>\nd\u2019une fa\u00e7on g\u00e9n\u00e9rale, mener directement ou indirectement toute action utile autoris\u00e9e par la loi ou le r\u00e8glement et par les pr\u00e9sents statuts.<\/p>\n<p>D\u2019autres moyens d\u2019action pourront le cas \u00e9ch\u00e9ant \u00eatre pr\u00e9cis\u00e9s par le r\u00e8glement int\u00e9rieur.<\/p>\n<p><strong>Article 4 : SIEGE SOCIAL<\/strong><\/p>\n<p>Le si\u00e8ge social du fonds de dotation est fix\u00e9 au 8 boulevard Edouard Herriot \u00e0 Marseille (13008).<\/p>\n<p>Il pourra \u00eatre modifi\u00e9 par d\u00e9cision du conseil d\u2019administration conforme aux dispositions de l\u2019article 17.1.<\/p>\n<p><strong>Article 5 : DUREE<\/strong><\/p>\n<p>Le fonds de dotation est constitu\u00e9 pour une dur\u00e9e ind\u00e9termin\u00e9e.<\/p>\n<p><strong>Article 6 : EXERCICE SOCIAL<\/strong><\/p>\n<p>L\u2019exercice social du fonds de dotation commence le 1er avril et se termine le 31 mars de l\u2019ann\u00e9e suivante.<\/p>\n<p>Par exception, le premier exercice du fonds d\u00e9butera au jour de la publication de sa cr\u00e9ation au Journal officiel et prendra fin le 31 mars 2020.<\/p>\n<p><strong>Article 7 : FONDATEURS<\/strong><\/p>\n<p>7.1 Le fondateur initial du fonds de dotation est Monsieur David SUSSMANN, et exer\u00e7ant la profession de chef d\u2019entreprise.<\/p>\n<p>7.2 Dans les autres cas, l\u2019admission d\u2019un nouveau fondateur, comme l\u2019exclusion d\u2019un fondateur, n\u00e9cessite l\u2019accord du fondateur initial formalis\u00e9 lors d&#8217;une r\u00e9union du conseil d\u2019administration.<\/p>\n<p>Le fondateur faisant l\u2019objet d\u2019une proc\u00e9dure d\u2019exclusion ne prend pas part au vote.<\/p>\n<p>Le fondateur initial ne peut faire l\u2019objet d\u2019aucune proc\u00e9dure d\u2019exclusion.<\/p>\n<p><strong>Article 8 : DOTATION EN CAPITAL<\/strong><\/p>\n<p>Le fonds de dotation est constitu\u00e9 avec une dotation initiale en capital de quinze mille (15.000) euros.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, la dotation en capital sera augment\u00e9e des donations et legs vis\u00e9s \u00e0 l\u2019article 910 du Code civil (m\u00eame si la proc\u00e9dure vis\u00e9e \u00e0 cet article du Code civil n\u2019est pas applicable au fonds de dotation) qui pourront lui \u00eatre consentis par toute personne physique ou morale, y compris ses membres fondateurs.<\/p>\n<p>La dotation en capital initiale est consomptible, pour permettre la r\u00e9alisation de l\u2019objet d\u00e9fini \u00e0 l\u2019article 2 des pr\u00e9sents statuts.<\/p>\n<p>Pour sa partie en num\u00e9raire, elle est plac\u00e9e dans les conditions vis\u00e9es \u00e0 l\u2019article R.931-10-21 du Code de la s\u00e9curit\u00e9 sociale.<\/p>\n<p><strong>Article 9 : RESSOURCES<\/strong><\/p>\n<p>Les ressources du fonds de dotation se composent des legs, des dons manuels spontan\u00e9s, et de ceux, le cas \u00e9ch\u00e9ant, issus d\u2019une campagne autoris\u00e9e d\u2019appel public \u00e0 la g\u00e9n\u00e9rosit\u00e9, des recettes provenant des activit\u00e9s du fonds de dotation, des revenus des biens de toute nature lui appartenant et plus g\u00e9n\u00e9ralement, de toute ressource non interdite par la loi et le r\u00e8glement.<\/p>\n<p>Lorsque le fonds re\u00e7oit d\u2019un tiers une affectation irr\u00e9vocable de biens et droits de toute nature, \u00e0 charge pour lui de les g\u00e9rer dans le but d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral souhait\u00e9 par ledit tiers, il ouvre une comptabilit\u00e9 divisionnaire distincte pour le suivi de cette affectation et de son emploi.<\/p>\n<p>Administration et fonctionnement<\/p>\n<p><strong>Article 10 : CONSEIL D\u2019ADMINISTRATION<\/strong><\/p>\n<p>10.1 Le fonds de dotation est administr\u00e9 par un conseil d\u2019administration compos\u00e9 de trois (3) membres au moins.<\/p>\n<p>Le fondateur initial ainsi que, le cas \u00e9ch\u00e9ant les autres fondateurs vis\u00e9s \u00e0 l\u2019article 7.2 sont membres de droit du conseil d&#8217;administration du Fonds de dotation et leur mandat est \u00e0 dur\u00e9e illimit\u00e9e.<\/p>\n<p>Les autres membres, personnes physiques ou morales, sont d\u00e9sign\u00e9s par le conseil d\u2019administration, apr\u00e8s accord du fondateur initial formalis\u00e9 selon les modalit\u00e9s pr\u00e9cis\u00e9es par le r\u00e8glement int\u00e9rieur.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, parmi ces autres membres d\u00e9sign\u00e9s, certains peuvent \u00eatre qualifi\u00e9s dans les domaines d\u2019intervention du fonds de dotation. Ils prennent le titre de personnalit\u00e9s qualifi\u00e9es et ne peuvent repr\u00e9senter plus du tiers du nombre total des membres du conseil d&#8217;administration.<\/p>\n<p>Les membres d\u00e9sign\u00e9s y compris les personnalit\u00e9s qualifi\u00e9es du Conseil d\u2019administration ont un mandat d\u2019une dur\u00e9e de trois (3) ann\u00e9es imm\u00e9diatement et ind\u00e9finiment renouvelable.<\/p>\n<p>Si en cas de d\u00e9c\u00e8s, de d\u00e9mission, d\u2019emp\u00eachement d\u00e9finitif ou d\u2019exclusion pour faute grave d\u2019un membre d\u00e9sign\u00e9, prononc\u00e9e par le Conseil d\u2019administration \u00e0 la majorit\u00e9 simple, le nombre de membres du Conseil d&#8217;administration devenait inf\u00e9rieur \u00e0 trois (3), il sera alors pourvu \u00e0 son remplacement par l\u2019ensemble des autres membres dans les trois (3) mois.<\/p>\n<p>Dans les autres hypoth\u00e8ses, le remplacement est facultatif.<\/p>\n<p>La proc\u00e9dure d\u2019exclusion d\u2019un membre d\u00e9sign\u00e9 pour faute grave pourra \u00eatre pr\u00e9cis\u00e9e par les dispositions du r\u00e8glement int\u00e9rieur et devra respecter le principe du contradictoire, le membre d\u00e9sign\u00e9 concern\u00e9 devant \u00eatre pr\u00e9alablement invit\u00e9 \u00e0 fournir ses explications orales ou \u00e9crites. Les fonctions de ce nouveau membre d\u00e9sign\u00e9 prennent fin \u00e0 la date \u00e0 laquelle aurait normalement expir\u00e9 le mandat de celui qu\u2019il remplace.<\/p>\n<p>Les membres du Conseil sont tenus d\u2019assister, selon les moyens et modalit\u00e9s vis\u00e9es \u00e0 l\u2019article 11 des pr\u00e9sents statuts, aux s\u00e9ances du Conseil. En cas d\u2019emp\u00eachement, un membre peut donner son pouvoir \u00e0 un autre administrateur, dans la limite d\u2019un pouvoir par membre.<\/p>\n<p>Le pr\u00e9sident du fonds de dotation est tenu de faire conna\u00eetre dans les trois (3) mois \u00e0 l\u2019autorit\u00e9 administrative comp\u00e9tente tous les changements intervenus dans la composition du Conseil d\u2019administration.<\/p>\n<p>Les repr\u00e9sentants du fonds de dotation doivent jouir du plein exercice de leurs droits civils.<\/p>\n<p>10.2 Le Conseil d\u2019administration comprend un pr\u00e9sident qui est nomm\u00e9, si le fondateur initial ne souhaite pas exercer les fonctions de pr\u00e9sident, par le fondateur initial selon les modalit\u00e9s pr\u00e9cis\u00e9es par le r\u00e8glement int\u00e9rieur. La dur\u00e9e du mandat du pr\u00e9sident est illimit\u00e9e si le mandat est exerc\u00e9 par le fondateur initial. Dans les autres hypoth\u00e8ses, la dur\u00e9e est de trois (3) ann\u00e9es, le mandat \u00e9tant imm\u00e9diatement et ind\u00e9finiment renouvelable.<\/p>\n<p>En aucun cas, la dur\u00e9e de son mandat ne peut d\u00e9passer la dur\u00e9e de sa qualit\u00e9 de membre du conseil d\u2019administration.<\/p>\n<p>Le pr\u00e9sident est charg\u00e9 d\u2019ex\u00e9cuter les d\u00e9cisions du Conseil d\u2019administration et d\u2019assurer le bon fonctionnement du fonds de dotation, dont la pr\u00e9sentation au Conseil d\u2019administration du rapport d\u2019activit\u00e9. Il repr\u00e9sente le fonds dans tous les actes de la vie civile et dispose du pouvoir de d\u00e9cider d\u2019une action en justice. Il ordonne les d\u00e9penses. Il peut donner d\u00e9l\u00e9gation dans des conditions d\u00e9finies par le Conseil d\u2019administration.<\/p>\n<p>Il repr\u00e9sente le fonds de dotation dans les rapports avec les tiers et en justice, tant en demande qu\u2019en d\u00e9fense, et ce, sans avoir \u00e0 justifier d\u2019un mandat express.<\/p>\n<p>Il est comp\u00e9tent pour solliciter les autorisations pour les appels publics \u00e0 la g\u00e9n\u00e9rosit\u00e9 apr\u00e8s information pr\u00e9alable du conseil d\u2019administration.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, le pr\u00e9sident pourra nommer, \u00e0 d\u00e9faut de vice-pr\u00e9sident, un des membres de droit du Conseil d\u2019administration afin de l\u2019assister ou de le suppl\u00e9er dans l\u2019exercice de ses fonctions. Il donnera pour cela une d\u00e9l\u00e9gation de pouvoir \u00e0 ce dernier.<\/p>\n<p>A d\u00e9faut de secr\u00e9taire, le pr\u00e9sident supervise les conditions dans lesquelles sont r\u00e9dig\u00e9s les proc\u00e8s-verbaux des r\u00e9unions du Conseil, sont r\u00e9alis\u00e9es les formalit\u00e9s d\u00e9claratives en pr\u00e9fecture, et conserv\u00e9es toutes les \u00e9critures concernant le fonctionnement du fonds de dotation, \u00e0 l\u2019exception de celles qui concernent la comptabilit\u00e9. Il pr\u00e9pare le rapport d\u2019activit\u00e9.<\/p>\n<p>A d\u00e9faut de tr\u00e9sorier, le pr\u00e9sident supervise les conditions dans lesquelles sont encaiss\u00e9es les recettes et acquitt\u00e9es les d\u00e9penses de la fondation. Il a le pouvoir de faire fonctionner les comptes ouverts par le fonds. Il peut donner d\u00e9l\u00e9gation. Il fait tenir une comptabilit\u00e9 r\u00e9guli\u00e8re de toutes les op\u00e9rations et rend compte au Conseil d\u2019administration qui statue sur la gestion. Il arr\u00eate les comptes.<\/p>\n<p>10.3 Le Conseil d\u2019administration comprend le cas \u00e9ch\u00e9ant, \u00e9galement un vice-pr\u00e9sident, un secr\u00e9taire et un tr\u00e9sorier. Leur mandat a une dur\u00e9e de trois (3) ans imm\u00e9diatement et ind\u00e9finiment renouvelable. En aucun cas, la dur\u00e9e de leur mandat ne peut d\u00e9passer la dur\u00e9e de leur qualit\u00e9 de membre.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, le vice-pr\u00e9sident, d\u00e9sign\u00e9 par le fondateur initial, est charg\u00e9 d\u2019assister ou de suppl\u00e9er le pr\u00e9sident dans l\u2019exercice de ses fonctions. Il peut recevoir d\u00e9l\u00e9gation de pouvoir de ce dernier.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, le secr\u00e9taire, \u00e9lu par le conseil d&#8217;administration, supervise les conditions dans lesquelles sont r\u00e9dig\u00e9s les proc\u00e8s-verbaux des r\u00e9unions du Conseil, sont r\u00e9alis\u00e9es les formalit\u00e9s d\u00e9claratives en pr\u00e9fecture, et conserv\u00e9es toutes les \u00e9critures concernant le fonctionnement du fonds de dotation, \u00e0 l\u2019exception de celles qui concernent la comptabilit\u00e9. Il pr\u00e9pare, avec le pr\u00e9sident, le rapport d\u2019activit\u00e9.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, le tr\u00e9sorier, \u00e9lu par le conseil d&#8217;administration, supervise les conditions dans lesquelles sont encaiss\u00e9es les recettes et acquitt\u00e9es les d\u00e9penses du Fonds de dotation. Il a le pouvoir de faire fonctionner les comptes ouverts par le fonds. Il peut donner d\u00e9l\u00e9gation. Il fait tenir une comptabilit\u00e9 r\u00e9guli\u00e8re de toutes les op\u00e9rations et rend compte au Conseil d\u2019administration qui statue sur la gestion. Il arr\u00eate les comptes.<\/p>\n<p><strong>Article 11 : REUNIONS DU CONSEIL D\u2019ADMINISTRATION<\/strong><\/p>\n<p>Le Conseil se r\u00e9unit au moins une (1) fois par an et aussi souvent que l\u2019int\u00e9r\u00eat du fonds l\u2019exige, sur convocation du Pr\u00e9sident ou de deux (2) membres du Conseil d\u2019administration, adress\u00e9e par lettre simple ou courriel, huit (8) jours avant la date pr\u00e9vue de la r\u00e9union.<\/p>\n<p>Cette convocation contenant la date, l\u2019heure et le lieu de r\u00e9union ainsi que l\u2019ordre du jour.<\/p>\n<p>Il peut se r\u00e9unir \u00e0 distance, par tout moyen utile (visioconf\u00e9rence et t\u00e9l\u00e9conf\u00e9rence).<\/p>\n<p>Il d\u00e9lib\u00e8re sur les questions mises \u00e0 l\u2019ordre du jour par le pr\u00e9sident et sur celles dont l\u2019inscription est demand\u00e9e par tout administrateur conform\u00e9ment \u00e0 la proc\u00e9dure pr\u00e9cis\u00e9e par le r\u00e8glement int\u00e9rieur.<\/p>\n<p>Le pr\u00e9sident du Conseil d\u2019administration doit toujours \u00eatre pr\u00e9sent ou repr\u00e9sent\u00e9 pour la validit\u00e9 des d\u00e9lib\u00e9rations du conseil d&#8217;administration.<\/p>\n<p>Si le quorum n\u2019est pas atteint, le conseil d&#8217;administration est convoqu\u00e9 \u00e0 nouveau et \u00e0 vingt-quatre (24) heures d\u2019intervalle au moins. Il d\u00e9lib\u00e8re sur le m\u00eame ordre du jour. Le Conseil d&#8217;administration ne pourra valablement se r\u00e9unir qu\u2019\u00e0 partir du moment o\u00f9 le pr\u00e9sident sera pr\u00e9sent ou repr\u00e9sent\u00e9.<\/p>\n<p>Le pr\u00e9sident en exercice du Conseil d\u2019administration pr\u00e9side la s\u00e9ance. A d\u00e9faut, la s\u00e9ance est pr\u00e9sid\u00e9e par le vice-pr\u00e9sident s\u2019il est d\u00e9sign\u00e9 ou \u00e0 d\u00e9faut par le membre \u00e9lu en s\u00e9ance \u00e0 la majorit\u00e9 des voix des membres pr\u00e9sents ou repr\u00e9sent\u00e9s.<\/p>\n<p>A d\u00e9faut de secr\u00e9taire, le pr\u00e9sident de s\u00e9ance peut d\u00e9signer le secr\u00e9taire de s\u00e9ance.<\/p>\n<p>En principe, les d\u00e9lib\u00e9rations du Conseil sont prises \u00e0 la majorit\u00e9 des voix des membres pr\u00e9sents ou repr\u00e9sent\u00e9s. N\u00e9anmoins, pour les d\u00e9cisions vis\u00e9es \u00e0 l\u2019article 7.2 (admission d\u2019un nouveau fondateur), \u00e0 l\u2019article 17 (modification des statuts et transformation) et \u00e0 l\u2019article 18 (dissolution \u2013 liquidation et fusion), l\u2019accord pr\u00e9alable du fondateur initial, formalis\u00e9 selon les modalit\u00e9s pr\u00e9cis\u00e9es par le r\u00e8glement int\u00e9rieur, est pr\u00e9alablement requis pour que les d\u00e9lib\u00e9rations soient valables.<\/p>\n<p>En toute hypoth\u00e8se, chaque membre ne peut recevoir plus de deux (2) pouvoirs et en cas de partage \u00e9gal des voix, celle du pr\u00e9sident est toujours pr\u00e9pond\u00e9rante.<\/p>\n<p>Il est tenu proc\u00e8s-verbal des s\u00e9ances, lequel est sign\u00e9 par le pr\u00e9sident de s\u00e9ance et, le cas \u00e9ch\u00e9ant, par le secr\u00e9taire de s\u00e9ance.<\/p>\n<p>Toute personne dont l\u2019avis est utile peut \u00eatre appel\u00e9e par le pr\u00e9sident \u00e0 assister, avec voix consultative, aux s\u00e9ances du Conseil d\u2019administration.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, des repr\u00e9sentants des commissions ad\u2019 hoc peuvent \u00eatre invit\u00e9s par le pr\u00e9sident \u00e0 si\u00e9ger avec voix consultative au conseil d&#8217;administration.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, le pr\u00e9sident peut proposer au conseil d&#8217;administration d\u2019accorder la qualit\u00e9 de membre consultatif \u00e0 toute personne physique ou morale et ce, dans les conditions pr\u00e9vues par le r\u00e8glement int\u00e9rieur. Ces membres participent \u00e0 toutes les r\u00e9unions du conseil d&#8217;administration avec voix consultative.<\/p>\n<p><strong>Article 12 : GESTION DESINTERESSEE<\/strong><\/p>\n<p>Les fonctions de membre du Conseil d\u2019administration et de membres des autres organes du fonds de dotation sont gratuites.<\/p>\n<p>Des remboursements de frais \u00e0 l\u2019euro pr\u00e8s sont seuls possibles sur justificatifs, dans les conditions fix\u00e9es par le Conseil d\u2019administration et selon les modalit\u00e9s d\u00e9finies, le cas \u00e9ch\u00e9ant, par le r\u00e8glement int\u00e9rieur.<\/p>\n<p><strong>Article 13 : ATTRIBUTIONS<\/strong><\/p>\n<p>13.1 Le Conseil d\u2019administration prend toutes les d\u00e9cisions dans l\u2019int\u00e9r\u00eat du fonds de dotation.<\/p>\n<p>Notamment :<\/p>\n<p>Il arr\u00eate le programme d\u2019action du fonds de dotation ;<br \/>\nIl adopte le rapport d\u2019activit\u00e9 qui lui est pr\u00e9sent\u00e9 annuellement ;<br \/>\nIl vote, sur proposition du pr\u00e9sident, le budget et ses modifications ;<br \/>\nIl re\u00e7oit, discute et approuve les comptes de l\u2019exercice clos qui lui sont pr\u00e9sent\u00e9s par le pr\u00e9sident avec pi\u00e8ces justificatives \u00e0 l\u2019appui ;<br \/>\nIl autorise les actes et engagements d\u00e9passant le cadre des pouvoirs propres du pr\u00e9sident, notamment toute modification des statuts ou dissolution du fonds de dotation ;<br \/>\nIl adopte et modifie le r\u00e8glement int\u00e9rieur\u00a0;<br \/>\nIl accepte les dons et les legs et autorise, en dehors de la gestion courante, les acquisitions et cessions de biens mobiliers et immobiliers, les march\u00e9s, les baux et les contrats de location, la constitution d\u2019hypoth\u00e8ques et les emprunts ainsi que les cautions et garanties accord\u00e9es au nom du fonds ;<br \/>\nIl proc\u00e8de \u00e0 la nomination et au renouvellement du commissaire aux comptes et de son suppl\u00e9ant choisis sur la liste mentionn\u00e9e \u00e0 l\u2019article L. 822-1 du code de commerce ;<br \/>\nIl fixe, le cas \u00e9ch\u00e9ant, les conditions de recrutement et de r\u00e9mun\u00e9ration du personnel ; il nomme, apr\u00e8s avis conforme du pr\u00e9sident, le directeur g\u00e9n\u00e9ral du fonds de dotation ;<br \/>\nIl d\u00e9signe ses repr\u00e9sentants admis \u00e0 participer \u00e0 l\u2019administration des organismes \u00e0 but non lucratif qu\u2019il soutient ou \u00e0 effectuer des missions d\u2019audit au sein de ces derniers ;<br \/>\nIl est tenu inform\u00e9 par le pr\u00e9sident de tout projet de convention engageant le fonds de dotation et d\u00e9lib\u00e8re sur les conventions entrant dans le champ de l\u2019article L. 612-5 du code de commerce ; dans ce cas, il se prononce hors la pr\u00e9sence de la personne int\u00e9ress\u00e9e ;<br \/>\nIl peut accorder au pr\u00e9sident, en-de\u00e7\u00e0 d\u2019un montant qu\u2019il d\u00e9termine, une d\u00e9l\u00e9gation permanente pour les cessions et acquisitions de biens mobiliers et immobiliers ainsi que pour l\u2019acceptation des donations et des legs et ce, selon les modalit\u00e9s pr\u00e9cis\u00e9es par le r\u00e8glement int\u00e9rieur.<\/p>\n<p>13.2 Commission ad hoc :<\/p>\n<p>Le Conseil d\u2019administration peut cr\u00e9er une ou plusieurs commissions, charg\u00e9s de l\u2019assister dans toutes les actions men\u00e9es par le fonds de dotation.<\/p>\n<p>Leurs attributions, leur organisation et leurs r\u00e8gles de fonctionnement sont fix\u00e9es par les pr\u00e9sents statuts et\/ou, le cas \u00e9ch\u00e9ant par une d\u00e9lib\u00e9ration du Conseil d\u2019administration les instituant.<\/p>\n<p>13.3 Comit\u00e9 des experts\u00a0:<\/p>\n<p>Le cas \u00e9ch\u00e9ant, le Conseil d\u2019administration peut instituer un Comit\u00e9 des experts\u00a0compos\u00e9 de personnalit\u00e9s venant d\u2019horizons multiples pouvant apporter aux activit\u00e9s du fonds de dotation des observations pertinentes mais \u00e9galement un r\u00e9seau utile \u00e0 ce dernier.<\/p>\n<p>Le Comit\u00e9 des experts\u00a0est compos\u00e9 de personnes physiques ou morales qui en auraient manifest\u00e9 un int\u00e9r\u00eat, propos\u00e9es par au moins un membre du conseil d&#8217;administration et ayant \u00e9t\u00e9 d\u00e9sign\u00e9es par le conseil d&#8217;administration, la voix du pr\u00e9sident devant \u00eatre dans la majorit\u00e9.<\/p>\n<p>Le Comit\u00e9 des experts\u00a0\u00e9lit en son sein un pr\u00e9sident selon les modalit\u00e9s pr\u00e9cis\u00e9es par le r\u00e8glement int\u00e9rieur.<\/p>\n<p>Les attributions, l\u2019organisation et les r\u00e8gles de fonctionnement du comit\u00e9, les pr\u00e9rogatives de son pr\u00e9sident, ainsi que les liens entre le Comit\u00e9 des experts\u00a0et les autres organes du fonds de dotation seront fix\u00e9es par le r\u00e8glement int\u00e9rieur du fonds de dotation.<\/p>\n<p>13.4 Directeur G\u00e9n\u00e9ral :<\/p>\n<p>Le cas \u00e9ch\u00e9ant, le pr\u00e9sident propose au Conseil d\u2019administration, pour assurer la direction g\u00e9n\u00e9rale du fonds de dotation sur le plan administratif, financier, technique, un directeur qui prend le titre de directeur g\u00e9n\u00e9ral.<\/p>\n<p>Le directeur g\u00e9n\u00e9ral peut soit \u00eatre un b\u00e9n\u00e9vole, soit \u00eatre embauch\u00e9 et licenci\u00e9 par le Conseil d\u2019administration qui fixe sa r\u00e9mun\u00e9ration, soit un salari\u00e9 mis \u00e0 disposition par un m\u00e9c\u00e8ne.<\/p>\n<p>Le cadre et la nature des d\u00e9l\u00e9gations de pouvoirs qui peuvent lui \u00eatre confi\u00e9es rel\u00e8vent de la comp\u00e9tence du Conseil d\u2019administration ou sont fix\u00e9s le r\u00e8glement int\u00e9rieur.<\/p>\n<p><strong>Article 14 : COMITE CONSULTATIF<\/strong><\/p>\n<p>Si la dotation en capital du fonds est sup\u00e9rieure \u00e0 un (1) million d\u2019euros, un comit\u00e9 consultatif devra \u00eatre institu\u00e9.<\/p>\n<p>Ce comit\u00e9 sera compos\u00e9 de personnalit\u00e9s qualifi\u00e9es ext\u00e9rieures au fonds de dotation nomm\u00e9es pour une dur\u00e9e d\u00e9termin\u00e9e par les membres du Conseil d\u2019administration du fonds de dotation.<\/p>\n<p>Le comit\u00e9 aura pour mission de donner son avis au Conseil d\u2019administration sur :<\/p>\n<p>la politique financi\u00e8re du fonds et sur la gestion de sa tr\u00e9sorerie, en mesurant notamment l\u2019\u00e9volution du risque financier, ainsi que sur toute prise de participation \u00e9ventuelle ;<br \/>\nla bonne utilisation, pour chaque programme d\u2019importance significative, du financement conform\u00e9ment \u00e0 la mission et aux objectifs du fonds ;<br \/>\nla bonne utilisation des dons par ces b\u00e9n\u00e9ficiaires.<\/p>\n<p>Pour mener \u00e0 bien sa mission, il peut r\u00e9aliser des \u00e9tudes et des expertises.<\/p>\n<p>Les r\u00e8gles de composition et de fonctionnement du comit\u00e9 consultatif seront fix\u00e9es ou compl\u00e9t\u00e9es par\u00a0le r\u00e8glement int\u00e9rieur.<\/p>\n<p><strong>Article 15 : FONDS INDIVIDUALISES<\/strong><\/p>\n<p>Le Conseil d\u2019administration ratifie la cr\u00e9ation de fonds individualis\u00e9s, non dot\u00e9s de la personnalit\u00e9 morale, plac\u00e9s sous le contr\u00f4le du fonds de dotation et d\u00e9di\u00e9s au financement d\u2019activit\u00e9s vis\u00e9es par le premier alin\u00e9a de l\u2019article 2 des pr\u00e9sents statuts.<\/p>\n<p>Il re\u00e7oit et examine les comptes et les rapports moraux et financiers qui lui sont adress\u00e9s chaque ann\u00e9e par les fonds individualis\u00e9s comme justification de l\u2019emploi des fonds re\u00e7us.<\/p>\n<p>Il fixe, dans le r\u00e8glement int\u00e9rieur, la proc\u00e9dure applicable aux demandeurs \u00e0 la cr\u00e9ation d\u2019un fonds individualis\u00e9, les modalit\u00e9s de gestion des comptes et la dur\u00e9e de fonctionnement des fonds individualis\u00e9s par le fonds.<\/p>\n<p>Il d\u00e9cide par une d\u00e9lib\u00e9ration motiv\u00e9e, et apr\u00e8s avoir pr\u00e9alablement entendus les personnes concern\u00e9es, de mettre un terme aux fonds individualis\u00e9s qui ne respectent pas les obligations qui leur sont impos\u00e9es par le fonds de dotation, ou dont le but ou les activit\u00e9s ne sont plus compatibles avec celles du fonds de dotation, ou dont la gestion est de nature \u00e0 compromettre l\u2019exercice de ses activit\u00e9s propres.<\/p>\n<p><strong>Article 16 : RAPPORT SPECIAL SUR LES FONDS INDIVIDUALISES<\/strong><\/p>\n<p>Le Conseil d\u2019administration approuve chaque ann\u00e9e un rapport sp\u00e9cial pr\u00e9sent\u00e9 par le pr\u00e9sident qui donne toutes pr\u00e9cisions utiles notamment sur :<\/p>\n<p>l\u2019organisation et le fonctionnement des comptes des fonds individualis\u00e9s ;<br \/>\nles informations qui lui ont \u00e9t\u00e9 transmises en application du 2\u00e8me alin\u00e9a de l\u2019article 15 (rapports des fonds individualis\u00e9s) ;<br \/>\nles nouveaux fonds individualis\u00e9s et ceux qui ont fait l\u2019objet d\u2019une liquidation.<\/p>\n<p>Modification des statuts et dissolution<\/p>\n<p><strong>Article 17 : MODIFICATION ET TRANSFORMATION<\/strong><\/p>\n<p>17.1. Les pr\u00e9sents statuts ne pourront \u00eatre modifi\u00e9s que par une d\u00e9lib\u00e9ration du Conseil d\u2019administration.<\/p>\n<p>Les d\u00e9cisions sont prises \u00e0 la majorit\u00e9 des membres votants pr\u00e9sents ou repr\u00e9sent\u00e9s. En toutes hypoth\u00e8ses, l\u2019accord pr\u00e9alable du fondateur initial, formalis\u00e9 selon les modalit\u00e9s pr\u00e9cis\u00e9es par le r\u00e8glement int\u00e9rieur, est pr\u00e9alablement requis pour que la d\u00e9cision du conseil d&#8217;administration soit effective.<\/p>\n<p>Ces modifications sont d\u00e9clar\u00e9es sans d\u00e9lai en Pr\u00e9fecture du d\u00e9partement du lieu du si\u00e8ge.<\/p>\n<p>17.2. Le Fonds de dotation pourra \u00eatre transform\u00e9 en une fondation reconnue d\u2019utilit\u00e9 publique sous r\u00e9serve d\u2019obtention d\u2019un d\u00e9cret en Conseil d\u2019\u00c9tat, sans donner lieu \u00e0 dissolution ni \u00e0 cr\u00e9ation d\u2019une personne morale nouvelle.<\/p>\n<p>La transformation du Fonds de dotation est d\u00e9cid\u00e9e par une d\u00e9lib\u00e9ration du conseil d\u2019administration.<\/p>\n<p>Les d\u00e9cisions sont prises \u00e0 la majorit\u00e9 des membres votants pr\u00e9sents ou repr\u00e9sent\u00e9s. En toutes hypoth\u00e8ses, l\u2019accord pr\u00e9alable du fondateur intial, formalis\u00e9 selon les modalit\u00e9s pr\u00e9cis\u00e9es par le r\u00e8glement int\u00e9rieur, est pr\u00e9alablement requis pour que la d\u00e9cision du conseil d&#8217;administration soit effective.<\/p>\n<p><strong>Article 18 : DISSOLUTION ET LIQUIDATION &#8211; FUSION<\/strong><\/p>\n<p>18.1 La dissolution volontaire du fonds de dotation ne pourra intervenir qu\u2019avec le consentement pr\u00e9alable du fondateur initial, formalis\u00e9 selon les modalit\u00e9s pr\u00e9cis\u00e9es par le r\u00e8glement int\u00e9rieur, et par une d\u00e9cision du conseil d&#8217;administration du fonds de dotation.<\/p>\n<p>Les d\u00e9cisions sont prises \u00e0 la majorit\u00e9 des membres votants pr\u00e9sents ou repr\u00e9sent\u00e9s. En toutes hypoth\u00e8ses, la voix de pr\u00e9sident doit \u00eatre dans la majorit\u00e9 pour que la d\u00e9cision du conseil d&#8217;administration soit effective.<\/p>\n<p>Le Conseil d\u2019administration, convoqu\u00e9 par le fondateur initial, d\u00e9signe alors un ou plusieurs liquidateurs qu\u2019il charge de proc\u00e9der \u00e0 la liquidation des biens du fonds de dotation et auquel il conf\u00e8re tous les pouvoirs n\u00e9cessaires pour mener \u00e0 bien cette mission.<\/p>\n<p>La liquidation des comptes des fonds individualis\u00e9s est effectu\u00e9e pr\u00e9alablement \u00e0 la liquidation des biens du fonds.<\/p>\n<p>Le Conseil d\u2019administration attribue, apr\u00e8s accord pr\u00e9alable du fondateur initial, l\u2019actif net \u00e0 un ou plusieurs fonds de dotation ou fondations reconnues d\u2019utilit\u00e9 publique exer\u00e7ant des activit\u00e9s similaires.<\/p>\n<p>Ces d\u00e9lib\u00e9rations sont adress\u00e9es sans d\u00e9lai en Pr\u00e9fecture du d\u00e9partement du lieu du si\u00e8ge social.<\/p>\n<p>18.2 La fusion par absorption ou par cr\u00e9ation d\u2019une structure nouvelle, la scission ou l\u2019apport partiel d\u2019actif du fonds de dotation au profit d\u2019une autre structure ne peut intervenir qu\u2019avec le consentement pr\u00e9alable du fondateur initial, formalis\u00e9 selon les modalit\u00e9s pr\u00e9cis\u00e9es par le r\u00e8glement int\u00e9rieur, et par une d\u00e9cision du conseil d&#8217;administration du fonds de dotation.<\/p>\n<p>Les d\u00e9cisions sont prises \u00e0 la majorit\u00e9 des membres votants pr\u00e9sents ou repr\u00e9sent\u00e9s. En toutes hypoth\u00e8ses, la voix de pr\u00e9sident doit \u00eatre dans la majorit\u00e9 pour que la d\u00e9cision du conseil d&#8217;administration soit effective.<\/p>\n<p>Ces modifications sont d\u00e9clar\u00e9es sans d\u00e9lai en Pr\u00e9fecture du d\u00e9partement du lieu du si\u00e8ge.<\/p>\n<p>Contr\u00f4le et r\u00e8glement int\u00e9rieur<\/p>\n<p><strong>Article 19 : CONTROLE<\/strong><\/p>\n<p>Le rapport d\u2019activit\u00e9, les comptes et le rapport du commissaire aux comptes sont adress\u00e9s chaque ann\u00e9e en Pr\u00e9fecture du d\u00e9partement du lieu du si\u00e8ge social par lettre recommand\u00e9e avec accus\u00e9 de r\u00e9ception.<\/p>\n<p>Les documents autres que ceux cit\u00e9s \u00e0 l\u2019alin\u00e9a pr\u00e9c\u00e9dent sont consultables au si\u00e8ge social du fonds de dotation sur demande pr\u00e9alable et sont syst\u00e9matiquement communiqu\u00e9s dans les meilleurs d\u00e9lais au fondateur initial et, le cas \u00e9ch\u00e9ant, autres fondateurs.<\/p>\n<p><strong>Article 20 : REGLEMENT INTERIEUR<\/strong><\/p>\n<p>Un r\u00e8glement int\u00e9rieur, qui pr\u00e9cise les modalit\u00e9s d\u2019application des pr\u00e9sents statuts, peut \u00eatre \u00e9tabli par le Conseil d\u2019administration.<\/p>\n<p><strong>Article 21 : COMPTES ANNUELS<\/strong><\/p>\n<p>Les comptes du fonds de dotation comprennent un bilan, un compte de r\u00e9sultat et une annexe. Ils sont \u00e9tablis suivant les r\u00e8gles \u00e9nonc\u00e9es par le r\u00e8glement n\u00b0 99-01 du 6 f\u00e9vrier 1999 du Comit\u00e9 de la r\u00e9glementation comptable, modifi\u00e9e pour les fonds de dotation suivant l\u2019avis n\u00b0 2009-01 du 6 f\u00e9vrier 2009 du Conseil national de la comptabilit\u00e9. Ils font ressortir, dans la mesure du possible, la tra\u00e7abilit\u00e9 qu\u2019ils ont affect\u00e9e.<\/p>\n<p>En cas d\u2019appel public \u00e0 la g\u00e9n\u00e9rosit\u00e9, l\u2019annexe des comptes annuels comprend les comptes d\u2019emploi des ressources collect\u00e9es aupr\u00e8s du\u00a0public, accompagn\u00e9 des informations relatives \u00e0 son \u00e9laboration.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, les contributions volontaires en nature, en comp\u00e9tence ou en industrie font l\u2019objet d\u2019une \u00e9valuation tant en produits qu\u2019en charges port\u00e9es au pied du compte de r\u00e9sultat.<\/p>\n<p>Dans un d\u00e9lai de six (6) mois suivant la fin de l\u2019exercice, le fonds de dotation publie ses comptes annuels et s\u2019assure de leur publication sur le site internet de la Direction de l\u2019information l\u00e9gale et administrative.<\/p>\n<p><strong>Article 22 : COMMISSAIRES AUX COMPTES<\/strong><\/p>\n<p>En tant que de besoin, il est d\u00e9sign\u00e9 :<\/p>\n<p>un commissaire aux comptes ;<br \/>\nun commissaire aux comptes suppl\u00e9ant.<\/p>\n<p>Les comptes annuels du fonds de dotation, ainsi que le rapport d\u2019activit\u00e9 annuel, lui sont communiqu\u00e9s au moins quarante-cinq (45) jours avant la date de la r\u00e9union du conseil d\u2019administration convoqu\u00e9 pour leur approbation.<\/p>\n<p>Le commissaire aux comptes, lors de sa certification des comptes annuels, doit v\u00e9rifier la concordance entre ces diff\u00e9rents documents.<\/p>\n<p>Lorsque le commissaire aux comptes invite le pr\u00e9sident du fonds de dotation \u00e0 faire d\u00e9lib\u00e9rer le conseil d\u2019administration sur des faits de nature \u00e0 compromettre la continuit\u00e9 de l\u2019activit\u00e9, il fixe la date, dans un d\u00e9lai qui ne peut exc\u00e9der huit (8) jours, l\u2019ordre du jour et, le cas \u00e9ch\u00e9ant, le lieu de la r\u00e9union du conseil d\u2019administration.<\/p>\n<p>Autres dispositions<\/p>\n<p><strong>Article 23 : POUVOIRS<\/strong><\/p>\n<p>Pour remplir les formalit\u00e9s l\u00e9gales (d\u00e9claration en pr\u00e9fecture, publication au JO, etc.), tous pouvoirs sont donn\u00e9s au porteur d&#8217;un exemplaire original des pr\u00e9sents statuts.<\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-263","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mentions l\u00e9gales - Pure Ocean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pure-ocean.org\/en\/mentions-legales\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentions l\u00e9gales - Pure Ocean\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pure-ocean.org\/en\/mentions-legales\/\" \/>\n<meta property=\"og:site_name\" content=\"Pure Ocean\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PureOceanFund\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T10:48:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PureOceanFund\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pure-ocean.org\\\/en\\\/mentions-legales\\\/\",\"url\":\"https:\\\/\\\/www.pure-ocean.org\\\/en\\\/mentions-legales\\\/\",\"name\":\"Mentions l\u00e9gales - Pure Ocean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pure-ocean.org\\\/#website\"},\"datePublished\":\"2017-09-19T14:35:42+00:00\",\"dateModified\":\"2025-04-29T10:48:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pure-ocean.org\\\/en\\\/mentions-legales\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pure-ocean.org\\\/en\\\/mentions-legales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pure-ocean.org\\\/en\\\/mentions-legales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.pure-ocean.org\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mentions l\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pure-ocean.org\\\/#website\",\"url\":\"https:\\\/\\\/www.pure-ocean.org\\\/\",\"name\":\"Pure Ocean\",\"description\":\"L&#039;innovation au service de l&#039;oc\u00e9an\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pure-ocean.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pure-ocean.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pure-ocean.org\\\/#organization\",\"name\":\"Pure Ocean\",\"url\":\"https:\\\/\\\/www.pure-ocean.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.pure-ocean.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pure-ocean.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/LOGO-FINAL-carre-03.png\",\"contentUrl\":\"https:\\\/\\\/www.pure-ocean.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/LOGO-FINAL-carre-03.png\",\"width\":472,\"height\":472,\"caption\":\"Pure Ocean\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pure-ocean.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PureOceanFund\\\/\",\"https:\\\/\\\/x.com\\\/PureOceanFund\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/27024658\\\/admin\\\/\",\"https:\\\/\\\/www.instagram.com\\\/pureoceanfund\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mentions l\u00e9gales - Pure Ocean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pure-ocean.org\/en\/mentions-legales\/","og_locale":"en_US","og_type":"article","og_title":"Mentions l\u00e9gales - Pure Ocean","og_url":"https:\/\/www.pure-ocean.org\/en\/mentions-legales\/","og_site_name":"Pure Ocean","article_publisher":"https:\/\/www.facebook.com\/PureOceanFund\/","article_modified_time":"2025-04-29T10:48:07+00:00","twitter_card":"summary_large_image","twitter_site":"@PureOceanFund","twitter_misc":{"Est. reading time":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pure-ocean.org\/en\/mentions-legales\/","url":"https:\/\/www.pure-ocean.org\/en\/mentions-legales\/","name":"Mentions l\u00e9gales - Pure Ocean","isPartOf":{"@id":"https:\/\/www.pure-ocean.org\/#website"},"datePublished":"2017-09-19T14:35:42+00:00","dateModified":"2025-04-29T10:48:07+00:00","breadcrumb":{"@id":"https:\/\/www.pure-ocean.org\/en\/mentions-legales\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pure-ocean.org\/en\/mentions-legales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pure-ocean.org\/en\/mentions-legales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.pure-ocean.org\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Mentions l\u00e9gales"}]},{"@type":"WebSite","@id":"https:\/\/www.pure-ocean.org\/#website","url":"https:\/\/www.pure-ocean.org\/","name":"Pure Ocean","description":"L&#039;innovation au service de l&#039;oc\u00e9an","publisher":{"@id":"https:\/\/www.pure-ocean.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pure-ocean.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.pure-ocean.org\/#organization","name":"Pure Ocean","url":"https:\/\/www.pure-ocean.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pure-ocean.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.pure-ocean.org\/wp-content\/uploads\/2022\/01\/LOGO-FINAL-carre-03.png","contentUrl":"https:\/\/www.pure-ocean.org\/wp-content\/uploads\/2022\/01\/LOGO-FINAL-carre-03.png","width":472,"height":472,"caption":"Pure Ocean"},"image":{"@id":"https:\/\/www.pure-ocean.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PureOceanFund\/","https:\/\/x.com\/PureOceanFund","https:\/\/www.linkedin.com\/company\/27024658\/admin\/","https:\/\/www.instagram.com\/pureoceanfund\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.pure-ocean.org\/en\/wp-json\/wp\/v2\/pages\/263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pure-ocean.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pure-ocean.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pure-ocean.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pure-ocean.org\/en\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":14,"href":"https:\/\/www.pure-ocean.org\/en\/wp-json\/wp\/v2\/pages\/263\/revisions"}],"predecessor-version":[{"id":38239,"href":"https:\/\/www.pure-ocean.org\/en\/wp-json\/wp\/v2\/pages\/263\/revisions\/38239"}],"wp:attachment":[{"href":"https:\/\/www.pure-ocean.org\/en\/wp-json\/wp\/v2\/media?parent=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}